{"id":551,"date":"2024-01-17T14:29:06","date_gmt":"2024-01-17T13:29:06","guid":{"rendered":"https:\/\/donesdeciencia.webs.upv.es\/cientifiques\/mae-jemison\/"},"modified":"2024-05-09T17:52:08","modified_gmt":"2024-05-09T15:52:08","slug":"mae-jemison","status":"publish","type":"cientifiques","link":"https:\/\/donesdeciencia.webs.upv.es\/es\/cientifiques\/mae-jemison\/","title":{"rendered":"Mae Jemison"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<p class=\"has-text-align-center\" id=\"playaudio\"><strong><a href=\"#\" rel=\"nofollow\">\u00c0udio descripci\u00f3<\/a><\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-audio\"><audio controls=\"\" src=\"https:\/\/donesdeciencia.webs.upv.es\/wp-content\/uploads\/2024\/01\/MAE-JEMISON-AD.mp3\"><\/audio><\/figure>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/donesdeciencia.webs.upv.es\/wp-content\/uploads\/2024\/01\/mae_jemison_p2-1024x681.jpg\" alt=\"\" class=\"wp-image-195\" srcset=\"https:\/\/donesdeciencia.webs.upv.es\/wp-content\/uploads\/2024\/01\/mae_jemison_p2-1024x681.jpg 1024w, https:\/\/donesdeciencia.webs.upv.es\/wp-content\/uploads\/2024\/01\/mae_jemison_p2-300x199.jpg 300w, https:\/\/donesdeciencia.webs.upv.es\/wp-content\/uploads\/2024\/01\/mae_jemison_p2-768x511.jpg 768w, https:\/\/donesdeciencia.webs.upv.es\/wp-content\/uploads\/2024\/01\/mae_jemison_p2-1536x1021.jpg 1536w, https:\/\/donesdeciencia.webs.upv.es\/wp-content\/uploads\/2024\/01\/mae_jemison_p2.jpg 1719w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" controls=\"\" src=\"https:\/\/donesdeciencia.webs.upv.es\/wp-content\/uploads\/2024\/01\/2021-03-25-ciencia-accesible-64501.mp4\"><\/video><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Graduada en Ingeniera Qu\u00edmica (1977) y doctora en Medicina (1981), Mae Jemison se convirti\u00f3 el 1992 en la primera mujer afroamericana que viaj\u00f3 al espacio. Su sue\u00f1o de ni\u00f1a se hizo realidad al formar parte de la tripulaci\u00f3n del transbordador espacial Endeavor.<\/p>\n\n\n\n<p>De madre profesora y paro supervisor de mantenimiento, fue una estudiante excelente con matr\u00edculas de honor en matem\u00e1ticas y ciencias, y con solo 16 a\u00f1os empez\u00f3 a estudiar en la Universidad de Stanford. Poco tiempo despu\u00e9s obtuvo su diploma en Ingenier\u00eda Qu\u00edmica y en Estudios Afroamericanos.<\/p>\n\n\n\n<p>De aqu\u00ed ingres\u00f3 en la Universidad de Cornell, donde se gradu\u00f3 en Medicina, y entre el 1983 y el 1985 trabaj\u00f3 como m\u00e9dica en los Cuerpos de Paz en Liberia y Sierra Leona.<\/p>\n\n\n\n<p>Despu\u00e9s de su misi\u00f3n volvi\u00f3 a los Estados Unidos y prosigui\u00f3 los estudios de ingenier\u00eda. Los vuelos de Sally Ride y Guion Bluford, la primera mujer y lo primero afroamericano, respectivamente, que la NASA envi\u00f3 en una misi\u00f3n en el espacio inspiraron Jemison para pedir su ingreso en la agencia espacial estadounidense en oto\u00f1o del 1985.<\/p>\n\n\n\n<p>Por fin, el 1992 lleg\u00f3 su momento: del 12 al 20 de septiembre de aquel a\u00f1o se desarroll\u00f3 su \u00fanica misi\u00f3n espacial, una misi\u00f3n colaborativa con Jap\u00f3n que adem\u00e1s ser\u00eda la n\u00famero 50 del programa de transbordadores. Como parte de su trabajo en la misi\u00f3n ejerci\u00f3 como especialista cient\u00edfica y llev\u00f3 a cabo una serie de experimentos sobre los mareos durante los vuelos; la p\u00e9rdida \u00f3sea en el espacio, y la ovulaci\u00f3n y fecundaci\u00f3n de ranas y el posterior desarrollo de los cucharones cuando no hay gravedad.<\/p>\n\n\n\n<p>En marzo del 1993, Jemison abandon\u00f3 la NASA con la intenci\u00f3n de crear su propia empresa. Desde entonces, ha sido profesora de ciencias en varias instituciones y ha puesto en marcha varios proyectos. El 1993 fund\u00f3 The Jemison Group, una consultora que trabaja para medir y aumentar el impacto sociocultural del dise\u00f1o y el desarrollo tecnol\u00f3gicos.<\/p>\n<\/div>\n<\/div>\n\n<iframe frameborder=\"0\" allowfullscreen=\"\" scrolling=\"no\" height=\"200\" style=\"width:100%;\" src=\"https:\/\/www.ivoox.com\/player_ej_113245175_6_1.html?c1=478693\" loading=\"lazy\"><\/iframe>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<div class=\"wp-block-group text-center has-blaubg-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-medium-font-size\">Artista: Galletamaria<\/h2>\n\n\n\n<p>Ubicaci\u00f3n: CEIP Torrefiel (C\/ Erudito Pag\u00e9s, 1 46019 Valencia)<\/p>\n\n\n\n<p><a href=\"https:\/\/donesdeciencia.webs.upv.es\/index.html#planol\">Plano<\/a><\/p>\n\n\n\n<p><strong>EMT<\/strong> L\u00edneas: 6, 12, 26, 60<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n<\/div>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n","protected":false},"featured_media":420,"menu_order":0,"template":"","class_list":["post-551","cientifiques","type-cientifiques","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/donesdeciencia.webs.upv.es\/es\/wp-json\/wp\/v2\/cientifiques\/551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/donesdeciencia.webs.upv.es\/es\/wp-json\/wp\/v2\/cientifiques"}],"about":[{"href":"https:\/\/donesdeciencia.webs.upv.es\/es\/wp-json\/wp\/v2\/types\/cientifiques"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/donesdeciencia.webs.upv.es\/es\/wp-json\/wp\/v2\/media\/420"}],"wp:attachment":[{"href":"https:\/\/donesdeciencia.webs.upv.es\/es\/wp-json\/wp\/v2\/media?parent=551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}